{"id":1797,"date":"2022-11-07T13:06:48","date_gmt":"2022-11-07T13:06:48","guid":{"rendered":"https:\/\/brainarts.nl\/?page_id=1797"},"modified":"2025-02-25T09:45:36","modified_gmt":"2025-02-25T09:45:36","slug":"rimborsi-dellassicurazione-sanitaria-e-pagamenti-autonomi","status":"publish","type":"page","link":"https:\/\/brainarts.nl\/it\/vergoedingen-zorgverzekering-en-zelfbetalen\/","title":{"rendered":"Rimborsi, assicurazioni sanitarie e pagamenti autonomi."},"content":{"rendered":"<div data-colibri-id=\"1797-c1\" class=\"style-1282 style-local-1797-c1 position-relative\">\n  <!---->\n  <div data-colibri-component=\"section\" data-colibri-id=\"1797-c2\" id=\"custom\" class=\"h-section h-section-global-spacing d-flex align-items-lg-center align-items-md-center align-items-center style-1283 style-local-1797-c2 position-relative\">\n    <!---->\n    <!---->\n    <div class=\"h-section-grid-container h-section-boxed-container\">\n      <div data-colibri-id=\"1797-c6\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-1972 style-local-1797-c6 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-1973-outer style-local-1797-c7-outer\">\n            <div data-colibri-id=\"1797-c7\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-1973 style-local-1797-c7 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"1797-c8\" class=\"h-global-transition-all h-heading style-1974 style-local-1797-c8 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-heading__outer style-1974 style-local-1797-c8\">\n                    <!---->\n                    <!---->\n                    <h2 class=\"\">L'aspetto finanziario<\/h2>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"1797-c9\" class=\"h-text h-text-component style-1975 style-local-1797-c9 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Di seguito troverete una panoramica il pi\u00f9 possibile completa di tutte le questioni riguardanti gli onorari, gli assicuratori e le possibilit\u00e0 di diventare clienti a pagamento. Se avete domande, contattateci. Saremo lieti di aiutarvi.<\/p>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div data-colibri-id=\"1797-c3\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-1284 style-local-1797-c3 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-1285-outer style-local-1797-c4-outer\">\n            <div data-colibri-id=\"1797-c4\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-1285 style-local-1797-c4 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"1797-c5\" class=\"h-text h-text-component style-1286 style-local-1797-c5 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <h5><strong><br>Assistenza non convenzionata<\/strong>\n                      <br>\n                    <\/h5>\n                    <p>Non lavoriamo con contratti con le assicurazioni sanitarie. Ci\u00f2 significa che dovrete dichiarare voi stessi una seduta di trattamento alla vostra assicurazione sanitaria. Naturalmente, dopo ogni seduta riceverete una fattura da parte nostra, che dovrete presentare alla vostra assicurazione sanitaria.<\/p>\n                    <h5>Tasse<\/h5>\n                    <p>Il rimborso con una polizza di restituzione \u00e8 di 100% (solo per le persone che avevano gi\u00e0 una polizza di restituzione nel 2024), con una polizza in natura o una polizza combinata il rimborso \u00e8 di solito tra il 70 e il 90 per cento per sessione, questo dipende dalla polizza e dalla cassa malattia.\n                      dalla polizza e dall'assicurazione sanitaria.<strong>&nbsp;&nbsp;<\/strong>\n                      <br>\n                    <\/p>\n                    <p>L'elenco completo delle tariffe \u00e8 disponibile all'indirizzo\n                      <a href=\"http:\/\/www.contractvrijepsycholoog.nl\" class=\"customize-unpreviewable\">www.contractvrijepsycholoog.nl<\/a>. Alcune assicurazioni sanitarie utilizzano le proprie tariffe \u00b4market-based\u00b4, che sono inferiori di qualche punto percentuale rispetto alla tariffa NZA. <\/p>\n                    <p>Potete sempre contattare il vostro assicuratore per informarvi sull'entit\u00e0 del rimborso.<\/p>\n                    <h5>Rischio proprio<\/h5>\n                    <p>Nel caso in cui la franchigia non sia ancora stata completamente utilizzata, l'assicuratore la prelever\u00e0 prima di procedere al rimborso. Questo vale per tutte le polizze. E sia per le cure convenzionate che per quelle non convenzionate.\n                      assistenza.<\/p>\n                    <h5><strong>Riferimento<\/strong><\/h5>\n                    <p>Le nostre cure vengono rimborsate solo in presenza di una prescrizione medica, che pu\u00f2 rivolgersi direttamente a noi tramite ZorgDomein. Si consiglia di organizzarsi per tempo.&nbsp;<\/p>\n                    <h5><strong>Tariffe<\/strong><\/h5>\n                    <p>Le nostre tariffe sono basate sul modello di prestazioni sanitarie della NZA (\n                      <a href=\"https:\/\/zorgprestatiemodel.nza.nl\" class=\"customize-unpreviewable\">https:\/\/zorgprestatiemodel.nza.nl\/<\/a>)<\/p>\n                    <h5><strong>Assistenza senza rimborso<\/strong><\/h5>\n                    <p>Alcuni trattamenti non sono coperti dalle assicurazioni sanitarie, e sono chiamati anche altri prodotti di cura. Nel nostro studio li trattiamo, ma applichiamo la tariffa oraria per i clienti che pagano da soli,\n                      cio\u00e8 100 euro per 45 minuti.<\/p>\n                    <h5><strong>Tariffa di soggiorno<\/strong><\/h5>\n                    <p>Se un appuntamento non viene cancellato con 24 ore di anticipo, verr\u00e0 addebitato un costo di permanenza pari a <strong>50 euro<\/strong>. Questo importo non pu\u00f2 essere richiesto all'assicurazione sanitaria.&nbsp;\n                      <br>&nbsp;<\/p>\n                    <h5><strong>Tariffe in generale<\/strong><\/h5>\n                    <p>L'importo della prestazione sanitaria da applicare dipende dalla professione, dal tipo di consulenza e dalla durata della stessa;&nbsp;<\/p>\n                    <ul>\n                      <li>Eseguiamo esclusivamente trattamenti monodisciplinari.&nbsp;<\/li>\n                      <li>La durata standard di un trattamento \u00e8 di 60 minuti. In consultazione e a seconda del trattamento, si pu\u00f2 derogare da questa durata.<\/li>\n                    <\/ul>\n                    <p>Offriamo trattamenti rimborsati dall'assicurazione di base, ma anche trattamenti per persone che vogliono pagarseli da sole. Quest'ultimo tipo di trattamento ha il vantaggio che le vostre esigenze di cura sono completamente gratuite, non c'\u00e8 nessuna limitazione\n                      non ci sono limiti al numero di sedute di trattamento e si ha quindi maggiore libert\u00e0 di decidere di quante cure si ha bisogno. Inoltre, con l'autopagamento la privacy \u00e8 totale e le informazioni che vi riguardano non saranno in alcun modo condivise con terzi.\n                      condivise.&nbsp;<\/p>\n                    <p>Quando le cure sono rimborsate dall'assicurazione di base, siamo obbligati per legge a compilare il questionario Honos della NZA. Dobbiamo condividere i risultati con la NZA, in forma pseudo-anonima, a scopo di ricerca.\n                      <a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwiUnv3UlOT5AhXEt6QKHVyqBHgQFnoECA0QAQ&amp;url=https%3A%2F%2Fwww.zorgprestatiemodel.nl%2Fnieuws%2Fzorgvraagtyperingstool-nza-online%2F&amp;usg=AOvVaw2zVW_7xmjikMJ8Jon6SX0H\" class=\"customize-unpreviewable\"> (leggi qui per maggiori informazioni).&nbsp;<\/a>\n                    <\/p>\n                    <h5><strong>Clienti autopaganti&nbsp;<\/strong><\/h5>\n                    <p>La tariffa standard per ogni consultazione per i clienti che pagano da soli \u00e8 la seguente: 125 euro per il colloquio di ingresso (compreso il piano di trattamento, la cartella dei compiti e l'uso dell'applicazione) e 100 euro per una sessione di trattamento.&nbsp;<\/p>\n                    <h5>Termini e condizioni generali<\/h5>\n                    <p>Cliccare\n                      <a href=\"https:\/\/drive.google.com\/file\/d\/1jV5iDMxTrXCqdoAb1zOTBvhlRFYYqZ1w\/view?usp=share_link\" class=\"customize-unpreviewable\">qui<\/a> Per visualizzare i nostri Termini e Condizioni e per\n                      <a href=\"https:\/\/drive.google.com\/file\/d\/1jV5iDMxTrXCqdoAb1zOTBvhlRFYYqZ1w\/view?usp=share_link\" class=\"customize-unpreviewable\">scaricare<\/a>.<\/p>\n                    <p>\n                      <br>\n                    <\/p>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <div data-colibri-component=\"section\" data-colibri-id=\"1797-c10\" id=\"reusable-sections\" class=\"h-section h-section-global-spacing d-flex align-items-lg-center align-items-md-center align-items-center style-1287 style-local-1797-c10 position-relative\">\n    <div class=\"background-wrapper\">\n      <div class=\"background-layer background-layer-media-container-lg\">\n        <!---->\n        <div class=\"overlay-layer\">\n          <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.6;\"><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"background-layer background-layer-media-container-md\">\n        <!---->\n        <div class=\"overlay-layer\">\n          <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.6;\"><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"background-layer background-layer-media-container\">\n        <!---->\n        <div class=\"overlay-layer\">\n          <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.6;\"><\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n    <!---->\n    <div class=\"h-section-grid-container h-section-boxed-container\">\n      <!---->\n      <div data-colibri-id=\"1797-c11\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-1288 style-local-1797-c11 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-1289-outer style-local-1797-c12-outer\">\n            <div data-colibri-id=\"1797-c12\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-1289 style-local-1797-c12 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"1797-c13\" class=\"h-global-transition-all h-heading style-1290 style-local-1797-c13 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-heading__outer style-1290 style-local-1797-c13\">\n                    <!---->\n                    <!---->\n                    <h3 class=\"\">Ci piace molto quando ci contattate!<\/h3>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"1797-c14\" class=\"h-lead h-text h-text-component style-1291 style-local-1797-c14 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Forse volete un consiglio o possiamo aiutarvi in qualche modo. Volete avere qualche spiegazione in pi\u00f9. O avete un'altra domanda da porci. Siamo a vostra disposizione e felici di aiutarvi.<\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"1797-c15\" class=\"h-x-container style-1292 style-local-1797-c15 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-x-container-inner style-dynamic-1797-c15-group style-1292-spacing style-local-1797-c15-spacing\"><span class=\"h-button__outer style-1293-outer style-local-1797-c16-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"https:\/\/brainarts.nl\/it\/questa-e-la-pagina-di-contatto-e-indirizzo-dello-psicologo-brainarts-utrecht\/\" data-colibri-id=\"1797-c16\" class=\"d-flex w-100 align-items-center h-button justify-content-lg-center justify-content-md-center justify-content-center style-1293 style-local-1797-c16 position-relative\"><!----><!----> <span>Contattate<\/span><\/a>\n                    <\/span>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Het financi\u00eble aspect Hieronder vindt je een zo volledig mogelijk overzicht van alle zaken omtrent vergoedingen, verzekeraars en opties om een zelf betalende client te worden. Als je vragen hebt, neem dan contact met ons op. We helpen je graag. Niet gecontracteerde zorg Wij werken niet met contracten met zorgverzekeraars. Dit houdt in dat je [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width-page.php","meta":{"footnotes":""},"class_list":["post-1797","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vergoedingen, zorgverzekering en zelfbetalen. - BrainArts Psycholoog<\/title>\n<meta name=\"description\" content=\"Alle informatie over vergoedingen, zorgverzekering en zelfbetalen. Je hoeft bij ons niet bij te betalen als het via je zorgverzekering gaat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brainarts.nl\/it\/rimborsi-dellassicurazione-sanitaria-e-pagamenti-autonomi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vergoedingen, zorgverzekering en zelfbetalen.\" \/>\n<meta property=\"og:description\" content=\"Alle informatie over vergoedingen, zorgverzekering en zelfbetalen. Je hoeft bij ons niet bij te betalen als het via je zorgverzekering gaat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brainarts.nl\/it\/rimborsi-dellassicurazione-sanitaria-e-pagamenti-autonomi\/\" \/>\n<meta property=\"og:site_name\" content=\"BrainArts Psycholoog\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T09:45:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rimborsi, assicurazioni sanitarie e pagamenti autonomi. - Psicologo BrainArts","description":"Tutte le informazioni su rimborsi, assicurazioni sanitarie e pagamenti autonomi. Non \u00e8 necessario pagare un extra con noi se si tratta di un'assicurazione sanitaria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brainarts.nl\/it\/rimborsi-dellassicurazione-sanitaria-e-pagamenti-autonomi\/","og_locale":"it_IT","og_type":"article","og_title":"Vergoedingen, zorgverzekering en zelfbetalen.","og_description":"Alle informatie over vergoedingen, zorgverzekering en zelfbetalen. Je hoeft bij ons niet bij te betalen als het via je zorgverzekering gaat.","og_url":"https:\/\/brainarts.nl\/it\/rimborsi-dellassicurazione-sanitaria-e-pagamenti-autonomi\/","og_site_name":"BrainArts Psycholoog","article_modified_time":"2025-02-25T09:45:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/","url":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/","name":"Rimborsi, assicurazioni sanitarie e pagamenti autonomi. - Psicologo BrainArts","isPartOf":{"@id":"https:\/\/brainarts.nl\/#website"},"datePublished":"2022-11-07T13:06:48+00:00","dateModified":"2025-02-25T09:45:36+00:00","description":"Tutte le informazioni su rimborsi, assicurazioni sanitarie e pagamenti autonomi. Non \u00e8 necessario pagare un extra con noi se si tratta di un'assicurazione sanitaria.","breadcrumb":{"@id":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brainarts.nl\/"},{"@type":"ListItem","position":2,"name":"Vergoedingen, zorgverzekering en zelfbetalen."}]},{"@type":"WebSite","@id":"https:\/\/brainarts.nl\/#website","url":"https:\/\/brainarts.nl\/","name":"Psicologo BrainArts","description":"Lets redesign Your mind","publisher":{"@id":"https:\/\/brainarts.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brainarts.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/brainarts.nl\/#organization","name":"Psicologo BrainArts","url":"https:\/\/brainarts.nl\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/brainarts.nl\/#\/schema\/logo\/image\/","url":"https:\/\/brainarts.nl\/wp-content\/uploads\/2023\/01\/cropped-cropped-BrainArts-logo-transparant-1.webp","contentUrl":"https:\/\/brainarts.nl\/wp-content\/uploads\/2023\/01\/cropped-cropped-BrainArts-logo-transparant-1.webp","width":189,"height":189,"caption":"BrainArts Psycholoog"},"image":{"@id":"https:\/\/brainarts.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/brainarts.nl\/it\/wp-json\/wp\/v2\/pages\/1797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brainarts.nl\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brainarts.nl\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brainarts.nl\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brainarts.nl\/it\/wp-json\/wp\/v2\/comments?post=1797"}],"version-history":[{"count":0,"href":"https:\/\/brainarts.nl\/it\/wp-json\/wp\/v2\/pages\/1797\/revisions"}],"wp:attachment":[{"href":"https:\/\/brainarts.nl\/it\/wp-json\/wp\/v2\/media?parent=1797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}