{"id":5926,"date":"2024-09-13T15:22:56","date_gmt":"2024-09-13T15:22:56","guid":{"rendered":"https:\/\/brainarts.nl\/?page_id=5926"},"modified":"2024-09-13T15:22:59","modified_gmt":"2024-09-13T15:22:59","slug":"conditions-generales-protocole-de-securite-et-de-surete","status":"publish","type":"page","link":"https:\/\/brainarts.nl\/fr\/algemene-voorwaarden-safe-and-sound-protocol\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales Safe and Sound Protocol"},"content":{"rendered":"<h4 class=\"wp-block-heading\">Conditions g\u00e9n\u00e9rales d'utilisation<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">Ch\u00e8re lectrice, cher lecteur,<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales, nous avons d\u00e9fini ce qui suit&nbsp;<strong>vos et mes droits et obligations&nbsp;<\/strong>sont. Ici, nous avons opt\u00e9 pour une version humaine et simple.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien entendu, le droit n\u00e9erlandais de la consommation s'applique toujours lorsque vous achetez nos services en tant que consommateur. Pour le reste, le droit n\u00e9erlandais s'applique lorsque les pr\u00e9sentes conditions g\u00e9n\u00e9rales ne pr\u00e9voient pas certains \u00e9v\u00e9nements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a une question que vous ne trouvez pas dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales ou quelque chose d'autre vous \u00e9chappe ? N'h\u00e9sitez pas \u00e0 nous contacter. Nous trouverons ensemble une solution appropri\u00e9e.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Article premier D\u00e9finitions<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous voyez l'un de ces mots dans ce texte, cela signifie formellement ceci :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Je, nous ou nous<\/strong>L'entreprise BrainArts\/ Safe and Sound Protocol, inscrite \u00e0 la Chambre de Commerce sous le num\u00e9ro 72561335. Le site web safeandsoundprotocol-ssp.nl en fait partie.&nbsp;<\/li>\n\n\n\n<li><strong>Vous\/vous ou vous<\/strong>: la personne physique ou morale qui a suivi le syst\u00e8me Safe and Sound Protocol ou Focus.<\/li>\n\n\n\n<li><strong>Offre en ligne<\/strong>: Toutes les formes d'\u00e9change d'informations entre nous et vous, que ce soit en ligne ou hors ligne, en groupe ou individuellement.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 2 Questions g\u00e9n\u00e9rales<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales s'appliquent \u00e0 toutes les offres, \u00e0 tous les devis, \u00e0 tous les accords et \u00e0 toutes les autres relations juridiques entre vous et nous.<\/li>\n\n\n\n<li>Nous pouvons modifier les pr\u00e9sentes conditions g\u00e9n\u00e9rales. La version la plus r\u00e9cente est toujours affich\u00e9e sur le site web safeandsoundprotocol-ssp.co.uk. Si les modifications affectent l'accord entre vous et nous, nous vous en informerons.<\/li>\n\n\n\n<li>Si une disposition des pr\u00e9sentes conditions g\u00e9n\u00e9rales n'est pas valable, parce qu'elle est nulle ou d\u00e9truite par vous, nous conviendrons ensemble d'une nouvelle r\u00e8gle, en vue d'atteindre le m\u00eame objectif.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 3 Notre offre<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nous faisons une offre \u00e9crite, y compris sur le site web et par le biais de d\u00e9pliants ou d'autres m\u00e9dias.<\/li>\n\n\n\n<li>Les offres sont valables pour la dur\u00e9e indiqu\u00e9e dans l'offre, apr\u00e8s quoi elles ne sont plus valables.<\/li>\n\n\n\n<li>Vous acceptez l'offre de la mani\u00e8re indiqu\u00e9e dans l'offre. Votre accord n'est pas d\u00e9finitif tant que vous n'avez pas pay\u00e9.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 4 Notre accord<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Le contrat est conclu lorsque vous acceptez l'offre et que vous avez pay\u00e9 la redevance convenue.<\/li>\n\n\n\n<li>Nous assumons une obligation de moyens dans le cadre de cet accord, mais nous ne garantissons pas l'obtention du r\u00e9sultat escompt\u00e9.<\/li>\n\n\n\n<li>Si cela s'av\u00e8re n\u00e9cessaire, nous pouvons faire ex\u00e9cuter (partiellement) l'accord par un tiers. Nous vous en informerons alors.<\/li>\n\n\n\n<li>S'il est n\u00e9cessaire de modifier l'accord, nous vous en informerons en temps utile et avant que la modification ne prenne effet.<\/li>\n\n\n\n<li>Nous pouvons changer, actualiser, remplacer ou modifier le contenu que nous fournissons conform\u00e9ment \u00e0 notre accord.<\/li>\n\n\n\n<li>Vous n'\u00eates pas satisfait ? Malheureusement, nous n'offrons pas de garantie \u2018satisfait ou rembours\u00e9\u2019. Toutefois, vous pouvez nous poursuivre en justice en cas de rupture de contrat. Veuillez consulter l'article sur la responsabilit\u00e9 plus loin dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales.<\/li>\n\n\n\n<li>Vous disposez d'un d\u00e9lai de 14 jours apr\u00e8s votre paiement pour nous demander un remboursement. Nous ne le faisons que si vous n'avez pas encore utilis\u00e9 l'application Unyte pour \u00e9couter. Une fois que vous avez \u00e9cout\u00e9, vous avez commenc\u00e9 \u00e0 utiliser le produit et il ne peut pas \u00eatre annul\u00e9. Ceci s'applique \u00e9galement \u00e0 Focus, avec Focus vous recevez \u00e9galement un kit de d\u00e9marrage complet. Nous aimerions que vous nous renvoyiez ce kit complet dans un d\u00e9lai de 14 jours et dans l'\u00e9tat o\u00f9 vous l'avez re\u00e7u avant de pouvoir proc\u00e9der au remboursement. Pour les retours, veuillez envoyer un courriel \u00e0&nbsp;<a href=\"mailto:post@brainarts.nl\">post@brainarts.nl<\/a>&nbsp;pour plus d'informations.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 5 Offre en ligne<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s paiement, vous obtenez 12 mois d'acc\u00e8s \u00e0 l'application Unyte. Ce faisant, vous pouvez utiliser l'int\u00e9gralit\u00e9 de SSP dans toutes ses variantes.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>L'acc\u00e8s \u00e0 l'application Unyte est personnel. Vous ne pouvez donc pas partager vos donn\u00e9es de connexion \u00e0 cette application et \u00e0 nos supports de cours avec d'autres personnes. Si vous prenez la formule familiale, vous ne pouvez la partager qu'avec votre famille. Nous appliquons alors un maximum de 5 personnes qui peuvent \u00e9couter. Si vous partagez vos donn\u00e9es de connexion avec quelqu'un sans respecter les r\u00e8gles ci-dessus, nous pourrons bloquer l'acc\u00e8s \u00e0 l'application et tous vos droits seront annul\u00e9s. Nous annulerons alors l'accord entre vous et nous et vous n'aurez pas droit \u00e0 un remboursement.<\/li>\n\n\n\n<li>L'acc\u00e8s \u00e0 l'application n'est possible qu'apr\u00e8s le paiement.<\/li>\n\n\n\n<li>Nous sommes un fournisseur d'Unyte et fournissons un acc\u00e8s \u00e0 leur application. Si l'application n'est pas disponible pendant un certain temps, nous compenserons ce temps en vous donnant un acc\u00e8s plus long pour la p\u00e9riode manquante. Par ailleurs, nous ne sommes pas responsables du non-fonctionnement de cette application, car nous n'avons aucune influence sur elle.<\/li>\n\n\n\n<li>En tant que fournisseur, nous avons acc\u00e8s \u00e0 une partie du logiciel de gestion des applications d'Unyte. Cela nous permet d'enregistrer les utilisateurs et d'activer et de d\u00e9sactiver les \u00e9l\u00e9ments du programme. Il nous permet \u00e9galement de voir combien de temps et \u00e0 quelle fr\u00e9quence vous \u00e9coutez. Mais nous ne pouvons pas voir \u00e0 quelle heure, o\u00f9 et avec qui vous \u00e9coutez. L'application n'a pas non plus acc\u00e8s \u00e0 votre cam\u00e9ra ou \u00e0 votre microphone, dans le sens o\u00f9 nous pouvons les utiliser. L'application vous demande d'activer un param\u00e8tre sur votre t\u00e9l\u00e9phone afin de ne pas \u00eatre d\u00e9rang\u00e9 lorsque vous \u00e9coutez. Pour \u00e9viter d'\u00eatre d\u00e9rang\u00e9, nous vous recommandons de mettre votre t\u00e9l\u00e9phone en mode avion apr\u00e8s avoir commenc\u00e9 \u00e0 \u00e9couter. Si vous avez des questions \u00e0 ce sujet, vous pouvez toujours nous contacter et v\u00e9rifier l'application elle-m\u00eame dans l'appstore et le playstore.<\/li>\n\n\n\n<li>Vous devez disposer d'une connexion internet pour t\u00e9l\u00e9charger les programmes choisis et l'application a besoin d'une connexion internet temporaire pour enregistrer l'endroit o\u00f9 vous vous \u00eates arr\u00eat\u00e9.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 6 - Orientations<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Vous recevrez des conseils de notre part au cours de ces 12 mois. Chez Focus, les consultations durent au moins 12 mois et parfois plus longtemps. Ces conseils s'appliquent \u00e9galement aux membres de votre famille si vous avez choisi le forfait familial. L'accompagnement se fait essentiellement par \u00e9crit au moyen de questions que vous pouvez nous poser par courriel ou par whatsapp. Si vous pr\u00e9f\u00e9rez nous appeler, nous pouvons toujours voir si cela est possible. Nous pouvons \u00e9galement vous proposer de nous appeler si votre question le permet. Nous faisons partie d'un cabinet de psychologie, vous pouvez donc compter sur des conseils appropri\u00e9s.<\/li>\n\n\n\n<li>Les conseils sont limit\u00e9s aux questions et probl\u00e8mes directement li\u00e9s au Safe and Sound Protocol et \u00e0 votre participation. Par exemple, si vous ressentez une tension en \u00e9coutant ou une autre forme d'inconfort et que vous ne savez pas quoi faire.<\/li>\n\n\n\n<li>Si, au cours de l'\u00e9coute, il s'av\u00e8re que des probl\u00e8mes apparaissent et n\u00e9cessitent une aide plus importante, contactez-nous imm\u00e9diatement pour obtenir des conseils. Et consultez imm\u00e9diatement votre m\u00e9decin traitant.<\/li>\n\n\n\n<li>Nous proposons \u00e9galement un parcours de soins complet par l'interm\u00e9diaire de notre cabinet de psychologie BrainArts. Le fait de suivre le Safe and Sound Protocol sur notre site web ne vous donne pas droit \u00e0 un traitement dans notre cabinet de psychologie. Cependant, nous pouvons toujours voir si un traitement suppl\u00e9mentaire est possible et appropri\u00e9.<\/li>\n\n\n\n<li>Si vous suivez le syst\u00e8me Focus chez nous, vous recevrez deux s\u00e9ances d'introduction de 45 minutes chacune, ainsi que des conseils \u00e9crits pendant la p\u00e9riode convenue. Ces s\u00e9ances peuvent se d\u00e9rouler en ligne ou dans notre cabinet. Nous conviendrons ensemble de ce qui nous convient le mieux. La p\u00e9riode standard d'acc\u00e8s au syst\u00e8me Focus via l'application Unyte est de 12 mois. Cette p\u00e9riode peut \u00eatre prolong\u00e9e de 12 mois suppl\u00e9mentaires d'un commun accord.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 7 - Exclusions et clauses de non-responsabilit\u00e9<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nous consacrons en permanence toute notre attention \u00e0 la composition et au contenu de l'information sur notre site web www.brainarts.nl. Malgr\u00e9 cet effort, il peut arriver que certaines informations soient incorrectes ou incompl\u00e8tes. Nous faisons \u00e9videmment de notre mieux pour \u00e9viter cela et si vous avez des ajouts ou des questions, ils sont toujours les bienvenus par e-mail.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des modifications peuvent \u00eatre apport\u00e9es \u00e0 l'information \u00e0 tout moment, sans pr\u00e9avis. Nous excluons toute responsabilit\u00e9 pour tout dommage, direct ou indirect, de quelque nature que ce soit, r\u00e9sultant ou li\u00e9 de quelque mani\u00e8re que ce soit \u00e0 l'utilisation de notre site web et\/ou des informations, ou \u00e0 l'impossibilit\u00e9 temporaire de consulter le site web. En outre, nous ne sommes pas responsables des dommages, directs ou indirects, r\u00e9sultant de l'utilisation des informations obtenues par le biais du site web.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le protocole \"Sain et sauf\" peut \u00eatre suivi seul ou en compl\u00e9ment d'un traitement existant. Nous conseillons explicitement de faire appel \u00e0 un sp\u00e9cialiste de la sant\u00e9 mentale ou des soins somatiques en cas de troubles qui perturbent un ou plusieurs domaines de la vie.  Dans ces cas, cependant, le protocole Sain et sauf peut compl\u00e9ter le traitement en cours dans un cadre de soins appropri\u00e9. Si vous avez des questions \u00e0 ce sujet, n'h\u00e9sitez pas \u00e0 nous contacter par e-mail ou par t\u00e9l\u00e9phone.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Article 8 Notre propri\u00e9t\u00e9 intellectuelle<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nous sommes les propri\u00e9taires l\u00e9gitimes de toutes les informations contenues dans notre site web et notre offre. Si nous ne sommes pas nous-m\u00eames les d\u00e9tenteurs des droits, nous disposons d'une licence d'utilisation.<\/li>\n\n\n\n<li>Il est important pour nous que notre contenu reste unique. Par cons\u00e9quent, nous ne vous donnons pas l'autorisation pr\u00e9alable de l'utiliser, de le partager, de le divulguer, de le copier ou de le reproduire. Si vous souhaitez le faire, demandez-nous d'abord l'autorisation par \u00e9crit.<\/li>\n\n\n\n<li>Vous ne pouvez stocker le mat\u00e9riel sous forme de copie personnelle ou de t\u00e9l\u00e9chargement que pour un usage strictement personnel.<\/li>\n\n\n\n<li>Vous ne pouvez pas proposer votre propre formation en ligne ou hors ligne ou quoi que ce soit de similaire \u00e0 des tiers sur la base des informations, du mat\u00e9riel et des travaux obtenus par notre interm\u00e9diaire dans le cadre de notre cours ou de notre site web.&nbsp;<\/li>\n\n\n\n<li>Si vous portez atteinte \u00e0 nos droits de propri\u00e9t\u00e9 intellectuelle ou si vous enfreignez l'une des r\u00e8gles susmentionn\u00e9es, nous pouvons vous infliger une amende de 5 000 euros par incident et de 5 000 euros par semaine ou partie de semaine pendant laquelle l'infraction se poursuit, jusqu'\u00e0 un maximum de 200 000 euros.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 9 Compensation et paiement<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Votre paiement doit \u00eatre effectu\u00e9 avant que vous puissiez acc\u00e9der \u00e0 l'application Unyte et \u00e0 notre cours.<\/li>\n\n\n\n<li>Vous recevrez une facture num\u00e9rique apr\u00e8s le paiement.<\/li>\n\n\n\n<li>Si vous annulez votre paiement ou si vous le r\u00e9cup\u00e9rez ou le faites r\u00e9cup\u00e9rer, nous bloquerons imm\u00e9diatement l'acc\u00e8s \u00e0 l'application Unyte et arr\u00eaterons votre coaching.<\/li>\n\n\n\n<li>Si votre inversion ou la mani\u00e8re dont vous r\u00e9cup\u00e9rez ou faites r\u00e9cup\u00e9rer votre argent n'est pas l\u00e9gale ou n'est pas conforme \u00e0 nos accords et conditions g\u00e9n\u00e9rales. Nous pouvons alors vous r\u00e9clamer ce montant. Le cas \u00e9ch\u00e9ant, nous pouvons faire appel \u00e0 une agence de recouvrement, ce qui entra\u00eene bien entendu des frais suppl\u00e9mentaires pour vous.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 10 Notre responsabilit\u00e9<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nous ne sommes pas responsables des dommages directs ou indirects caus\u00e9s par l'utilisation de l'application Unyte ou de notre cours. Cependant, si un dommage survient, nous essaierons de vous aider si vous nous le signalez.<\/li>\n\n\n\n<li>Vous avez le choix d'appliquer ou non les connaissances acquises dans le cadre du cours. Nous ne sommes pas responsables des cons\u00e9quences de ce choix ou de la mani\u00e8re dont vous appliquez les connaissances, ni des cons\u00e9quences ou dommages \u00e9ventuels pour vous.<\/li>\n\n\n\n<li>Nous ne sommes pas responsables des virus qui se trouvent sur votre ordinateur ou qui s'y introduisent, m\u00eame si c'est par le biais d'un e-mail ou d'un fichier provenant de nous.<\/li>\n\n\n\n<li>Nous ne pouvons pas garantir que l'application Unyte est toujours disponible. Si elle ne fonctionne pas, veuillez nous en informer via notre formulaire de contact ou \u00e0 l'adresse suivante&nbsp;<a href=\"mailto:post@brainarts.nl\">post@brainarts.nl<\/a>.<\/li>\n\n\n\n<li>Nous vous d\u00e9dommagerons toujours pour la p\u00e9riode pendant laquelle vous n'avez pas eu acc\u00e8s \u00e0 l'application. Pour ce faire, nous prolongeons votre temps d'acc\u00e8s total de la dur\u00e9e de l'indisponibilit\u00e9, une fois que l'application est \u00e0 nouveau disponible. Jusqu'\u00e0 pr\u00e9sent, cela ne s'est jamais produit, mais il est \u00e9vident qu'un probl\u00e8me technique peut toujours se produire une fois.<\/li>\n\n\n\n<li>Nous ne sommes responsables des dommages directs qu'en cas de d\u00e9faillance l\u00e9gale ou contractuelle et uniquement \u00e0 concurrence du montant de la facture.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Article 11 Autres dispositions et vie priv\u00e9e<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nous traitons vos donn\u00e9es personnelles avec soin. Ceci est d\u00e9crit plus en d\u00e9tail dans la d\u00e9claration de confidentialit\u00e9 et de cookies qui se trouve sur le site web www.brainarts.nl.<\/li>\n\n\n\n<li>Si nous demandons un avis ou si nous vous demandons si nous pouvons utiliser vos informations pour notre site web, nous le ferons toujours sous une forme anonyme. Si nous ne le faisons pas sous une forme anonyme, nous vous le demanderons \u00e9galement. Vous avez toujours le droit de faire modifier ou supprimer les informations affich\u00e9es vous concernant. Votre int\u00e9r\u00eat personnel est toujours plus important que le n\u00f4tre.<\/li>\n\n\n\n<li>Si vous publiez un avis sur nous ailleurs, les r\u00e8gles du site web sur lequel vous le publiez s'appliquent. Nous ne vous demandons jamais d'\u00eatre positif, nous vous demandons d'\u00eatre honn\u00eate. Vous n'\u00eates pas satisfait de quelque chose ? Veuillez nous contacter avant de publier un commentaire. Nous nous efforcerons toujours de trouver une solution appropri\u00e9e pour vous satisfaire \u00e0 nouveau.<\/li>\n\n\n\n<li>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales sont r\u00e9gies exclusivement par le droit n\u00e9erlandais.<\/li>\n\n\n\n<li>Les litiges sont soumis \u00e0 une juridiction comp\u00e9tente, \u00e0 savoir le tribunal d'arrondissement d'Utrecht.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ces conditions g\u00e9n\u00e9rales ont \u00e9t\u00e9 mises \u00e0 jour pour la derni\u00e8re fois le 22-07-2024.<\/p>","protected":false},"excerpt":{"rendered":"<p>Algemene voorwaarden Beste Lezer, In deze algemene voorwaarden hebben we vastgelegd wat&nbsp;jouw en mijn rechten en plichten&nbsp;zijn. We hebben hierbij gekozen voor een menselijke en simpele versie. Uiteraard is altijd het Nederlandse consumentenrecht van toepassing wanneer je onze diensten afneemt als consument. En geld voor al het overige het Nederlandse recht wanneer deze algemene voorwaarden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5926","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Algemene voorwaarden Safe and Sound Protocol - BrainArts Psycholoog<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Algemene voorwaarden Safe and Sound Protocol\" \/>\n<meta property=\"og:description\" content=\"Algemene voorwaarden Beste Lezer, In deze algemene voorwaarden hebben we vastgelegd wat&nbsp;jouw en mijn rechten en plichten&nbsp;zijn. We hebben hierbij gekozen voor een menselijke en simpele versie. Uiteraard is altijd het Nederlandse consumentenrecht van toepassing wanneer je onze diensten afneemt als consument. En geld voor al het overige het Nederlandse recht wanneer deze algemene voorwaarden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brainarts.nl\/fr\/conditions-generales-protocole-de-securite-et-de-surete\/\" \/>\n<meta property=\"og:site_name\" content=\"BrainArts Psycholoog\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T15:22:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales Safe and Sound Protocol - BrainArts Psychologue","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Algemene voorwaarden Safe and Sound Protocol","og_description":"Algemene voorwaarden Beste Lezer, In deze algemene voorwaarden hebben we vastgelegd wat&nbsp;jouw en mijn rechten en plichten&nbsp;zijn. We hebben hierbij gekozen voor een menselijke en simpele versie. Uiteraard is altijd het Nederlandse consumentenrecht van toepassing wanneer je onze diensten afneemt als consument. En geld voor al het overige het Nederlandse recht wanneer deze algemene voorwaarden [&hellip;]","og_url":"https:\/\/brainarts.nl\/fr\/conditions-generales-protocole-de-securite-et-de-surete\/","og_site_name":"BrainArts Psycholoog","article_modified_time":"2024-09-13T15:22:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brainarts.nl\/algemene-voorwaarden-safe-and-sound-protocol\/","url":"https:\/\/brainarts.nl\/algemene-voorwaarden-safe-and-sound-protocol\/","name":"Conditions g\u00e9n\u00e9rales Safe and Sound Protocol - BrainArts Psychologue","isPartOf":{"@id":"https:\/\/brainarts.nl\/#website"},"datePublished":"2024-09-13T15:22:56+00:00","dateModified":"2024-09-13T15:22:59+00:00","breadcrumb":{"@id":"https:\/\/brainarts.nl\/algemene-voorwaarden-safe-and-sound-protocol\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brainarts.nl\/algemene-voorwaarden-safe-and-sound-protocol\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brainarts.nl\/algemene-voorwaarden-safe-and-sound-protocol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brainarts.nl\/"},{"@type":"ListItem","position":2,"name":"Algemene voorwaarden Safe and Sound Protocol"}]},{"@type":"WebSite","@id":"https:\/\/brainarts.nl\/#website","url":"https:\/\/brainarts.nl\/","name":"Psychologue BrainArts","description":"Lets redesign Your mind","publisher":{"@id":"https:\/\/brainarts.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brainarts.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/brainarts.nl\/#organization","name":"Psychologue BrainArts","url":"https:\/\/brainarts.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/brainarts.nl\/#\/schema\/logo\/image\/","url":"https:\/\/brainarts.nl\/wp-content\/uploads\/2023\/01\/cropped-cropped-BrainArts-logo-transparant-1.webp","contentUrl":"https:\/\/brainarts.nl\/wp-content\/uploads\/2023\/01\/cropped-cropped-BrainArts-logo-transparant-1.webp","width":189,"height":189,"caption":"BrainArts Psycholoog"},"image":{"@id":"https:\/\/brainarts.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/brainarts.nl\/fr\/wp-json\/wp\/v2\/pages\/5926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brainarts.nl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brainarts.nl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brainarts.nl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brainarts.nl\/fr\/wp-json\/wp\/v2\/comments?post=5926"}],"version-history":[{"count":0,"href":"https:\/\/brainarts.nl\/fr\/wp-json\/wp\/v2\/pages\/5926\/revisions"}],"wp:attachment":[{"href":"https:\/\/brainarts.nl\/fr\/wp-json\/wp\/v2\/media?parent=5926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}