{"id":1797,"date":"2022-11-07T13:06:48","date_gmt":"2022-11-07T13:06:48","guid":{"rendered":"https:\/\/brainarts.nl\/?page_id=1797"},"modified":"2025-02-25T09:45:36","modified_gmt":"2025-02-25T09:45:36","slug":"erstattungen-von-krankenkassen-und-selbstzahler","status":"publish","type":"page","link":"https:\/\/brainarts.nl\/de\/vergoedingen-zorgverzekering-en-zelfbetalen\/","title":{"rendered":"Erstattungen, Krankenversicherungen und Selbstzahler."},"content":{"rendered":"<div data-colibri-id=\"1797-c1\" class=\"style-1282 style-local-1797-c1 position-relative\">\n  <!---->\n  <div data-colibri-component=\"section\" data-colibri-id=\"1797-c2\" id=\"custom\" class=\"h-section h-section-global-spacing d-flex align-items-lg-center align-items-md-center align-items-center style-1283 style-local-1797-c2 position-relative\">\n    <!---->\n    <!---->\n    <div class=\"h-section-grid-container h-section-boxed-container\">\n      <div data-colibri-id=\"1797-c6\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-1972 style-local-1797-c6 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-1973-outer style-local-1797-c7-outer\">\n            <div data-colibri-id=\"1797-c7\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-1973 style-local-1797-c7 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"1797-c8\" class=\"h-global-transition-all h-heading style-1974 style-local-1797-c8 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-heading__outer style-1974 style-local-1797-c8\">\n                    <!---->\n                    <!---->\n                    <h2 class=\"\">Der finanzielle Aspekt<\/h2>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"1797-c9\" class=\"h-text h-text-component style-1975 style-local-1797-c9 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Im Folgenden finden Sie einen m\u00f6glichst vollst\u00e4ndigen \u00dcberblick \u00fcber alle Fragen zu Geb\u00fchren, Versicherern und M\u00f6glichkeiten, Selbstzahler zu werden. Wenn Sie Fragen haben, wenden Sie sich bitte an uns. Wir helfen Ihnen gerne weiter.<\/p>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div data-colibri-id=\"1797-c3\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-1284 style-local-1797-c3 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-1285-outer style-local-1797-c4-outer\">\n            <div data-colibri-id=\"1797-c4\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-1285 style-local-1797-c4 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"1797-c5\" class=\"h-text h-text-component style-1286 style-local-1797-c5 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <h5><strong><br>Nicht-vertragliche Pflege<\/strong>\n                      <br>\n                    <\/h5>\n                    <p>Wir arbeiten nicht mit Vertr\u00e4gen mit Krankenversicherungen. Das bedeutet, dass Sie eine Behandlungssitzung selbst bei Ihrer Krankenkasse anmelden m\u00fcssen. Nat\u00fcrlich erhalten Sie von uns nach jeder Sitzung eine Rechnung, die Sie bei Ihrer Krankenkasse einreichen.<\/p>\n                    <h5>Geb\u00fchren<\/h5>\n                    <p>Die R\u00fcckerstattung bei einer R\u00fcckerstattungspolice betr\u00e4gt 100% (nur f\u00fcr Personen, die 2024 bereits eine R\u00fcckerstattungspolice hatten), bei einer Sachleistungspolice oder Kombinationspolice liegt die R\u00fcckerstattung in der Regel zwischen 70 und 90 Prozent pro Sitzung, dies h\u00e4ngt von der Police und der Krankenkasse ab\n                      von der Police und der Krankenkasse ab.<strong>&nbsp;&nbsp;<\/strong>\n                      <br>\n                    <\/p>\n                    <p>Eine vollst\u00e4ndige Liste der Geb\u00fchren finden Sie unter\n                      <a href=\"http:\/\/www.contractvrijepsycholoog.nl\" class=\"customize-unpreviewable\">www.contractvrijepsycholoog.nl<\/a>. Einige Krankenversicherer verwenden ihre eigenen \"marktbasierten\" Tarife, die einige Prozent unter dem NZA-Tarif liegen. <\/p>\n                    <p>Sie k\u00f6nnen sich jederzeit an Ihren Versicherer wenden, um sich \u00fcber die H\u00f6he der Erstattung zu erkundigen.<\/p>\n                    <h5>Eigenes Risiko<\/h5>\n                    <p>Falls Ihre Selbstbeteiligung noch nicht vollst\u00e4ndig ausgesch\u00f6pft ist, wird sie vom Versicherer gepr\u00fcft, bevor eine Erstattung erfolgt. Dies gilt f\u00fcr alle Vertr\u00e4ge. Und zwar sowohl f\u00fcr die vertragliche als auch f\u00fcr die nichtvertragliche Versorgung.\n                      Pflege.<\/p>\n                    <h5><strong>Referenz<\/strong><\/h5>\n                    <p>Unsere Leistungen werden nur dann erstattet, wenn eine \u00dcberweisung von einem Arzt vorliegt, der sich \u00fcber ZorgDomein direkt an uns wenden kann. Wir empfehlen, dies rechtzeitig zu veranlassen.&nbsp;<\/p>\n                    <h5><strong>Preise<\/strong><\/h5>\n                    <p>Unsere Tarife basieren auf dem Leistungsmodell der NZA f\u00fcr das Gesundheitswesen (\n                      <a href=\"https:\/\/zorgprestatiemodel.nza.nl\" class=\"customize-unpreviewable\">https:\/\/zorgprestatiemodel.nza.nl\/<\/a>)<\/p>\n                    <h5><strong>Pflege ohne Kostenerstattung<\/strong><\/h5>\n                    <p>Es gibt eine Reihe von Behandlungen, die nicht von den Krankenkassen \u00fcbernommen werden, diese werden auch als sonstige Pflegemittel bezeichnet. Diese behandeln wir zwar in unserer Praxis, aber wir wenden hier den Stundensatz f\u00fcr Selbstzahler an,\n                      n\u00e4mlich 100 Euro pro 45 Minuten.<\/p>\n                    <h5><strong>Fernbleibe-Tarif<\/strong><\/h5>\n                    <p>Wenn ein Termin nicht 24 Stunden im Voraus abgesagt wird, berechnen wir eine Abwesenheitsgeb\u00fchr von <strong>50 Euro<\/strong>. Dieser Betrag kann nicht bei einer Krankenkasse geltend gemacht werden.&nbsp;\n                      <br>&nbsp;<\/p>\n                    <h5><strong>Preise im Allgemeinen<\/strong><\/h5>\n                    <p>Die H\u00f6he des Krankengeldes h\u00e4ngt vom Beruf, der Art der Beratung und der Dauer dieser Leistung ab;&nbsp;<\/p>\n                    <ul>\n                      <li>Wir f\u00fchren nur monodisziplin\u00e4re Behandlungen durch.&nbsp;<\/li>\n                      <li>Die Standarddauer einer Behandlung betr\u00e4gt 60 Minuten. In Absprache und je nach Behandlung kann hiervon abgewichen werden<\/li>\n                    <\/ul>\n                    <p>Wir bieten sowohl Behandlungen an, die von der Grundversicherung erstattet werden, als auch Behandlungen f\u00fcr Personen, die sie selbst bezahlen m\u00f6chten. Letzteres hat den Vorteil, dass Ihr Pflegebedarf v\u00f6llig frei ist, es gibt keine Begrenzung\n                      Es gibt keine Begrenzung f\u00fcr die Anzahl der Behandlungen, und Sie k\u00f6nnen selbst entscheiden, wie viele Behandlungen Sie ben\u00f6tigen. Au\u00dferdem ist bei Selbstzahlern der Datenschutz gew\u00e4hrleistet, und es werden keinerlei Informationen \u00fcber Sie an Dritte\n                      weitergegeben.&nbsp;<\/p>\n                    <p>Wenn die Behandlung von der Grundversicherung erstattet wird, sind wir gesetzlich verpflichtet, den Honos-Fragebogen der NZA auszuf\u00fcllen. Wir m\u00fcssen diese Ergebnisse in pseudo-anonymisierter Form zu Forschungszwecken an das NZA weitergeben.\n                      <a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwiUnv3UlOT5AhXEt6QKHVyqBHgQFnoECA0QAQ&amp;url=https%3A%2F%2Fwww.zorgprestatiemodel.nl%2Fnieuws%2Fzorgvraagtyperingstool-nza-online%2F&amp;usg=AOvVaw2zVW_7xmjikMJ8Jon6SX0H\" class=\"customize-unpreviewable\"> (f\u00fcr weitere Informationen lesen Sie hier).&nbsp;<\/a>\n                    <\/p>\n                    <h5><strong>Selbstzahlende Kunden&nbsp;<\/strong><\/h5>\n                    <p>Der Standardtarif pro Konsultation f\u00fcr Selbstzahler ist wie folgt: 125 \u20ac f\u00fcr das Aufnahmegespr\u00e4ch (einschlie\u00dflich Behandlungsplan, Hausaufgabenmappe und Nutzung der App) und 100 \u20ac f\u00fcr eine Behandlungssitzung.&nbsp;<\/p>\n                    <h5>Allgemeine Bedingungen und Konditionen<\/h5>\n                    <p>Klicken Sie auf\n                      <a href=\"https:\/\/drive.google.com\/file\/d\/1jV5iDMxTrXCqdoAb1zOTBvhlRFYYqZ1w\/view?usp=share_link\" class=\"customize-unpreviewable\">hier<\/a> Um unsere Allgemeinen Gesch\u00e4ftsbedingungen einzusehen und um\n                      <a href=\"https:\/\/drive.google.com\/file\/d\/1jV5iDMxTrXCqdoAb1zOTBvhlRFYYqZ1w\/view?usp=share_link\" class=\"customize-unpreviewable\">herunterladen<\/a>.<\/p>\n                    <p>\n                      <br>\n                    <\/p>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <div data-colibri-component=\"section\" data-colibri-id=\"1797-c10\" id=\"reusable-sections\" class=\"h-section h-section-global-spacing d-flex align-items-lg-center align-items-md-center align-items-center style-1287 style-local-1797-c10 position-relative\">\n    <div class=\"background-wrapper\">\n      <div class=\"background-layer background-layer-media-container-lg\">\n        <!---->\n        <div class=\"overlay-layer\">\n          <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.6;\"><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"background-layer background-layer-media-container-md\">\n        <!---->\n        <div class=\"overlay-layer\">\n          <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.6;\"><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"background-layer background-layer-media-container\">\n        <!---->\n        <div class=\"overlay-layer\">\n          <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.6;\"><\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n    <!---->\n    <div class=\"h-section-grid-container h-section-boxed-container\">\n      <!---->\n      <div data-colibri-id=\"1797-c11\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-1288 style-local-1797-c11 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-1289-outer style-local-1797-c12-outer\">\n            <div data-colibri-id=\"1797-c12\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-1289 style-local-1797-c12 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"1797-c13\" class=\"h-global-transition-all h-heading style-1290 style-local-1797-c13 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-heading__outer style-1290 style-local-1797-c13\">\n                    <!---->\n                    <!---->\n                    <h3 class=\"\">Wir freuen uns, wenn Sie uns kontaktieren!<\/h3>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"1797-c14\" class=\"h-lead h-text h-text-component style-1291 style-local-1797-c14 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Vielleicht m\u00f6chten Sie einen Rat oder wir k\u00f6nnen Ihnen bei etwas helfen. Suchen Sie eine zus\u00e4tzliche Erkl\u00e4rung. Oder haben Sie eine andere Frage an uns. Wir sind f\u00fcr Sie da und helfen Ihnen gerne.<\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"1797-c15\" class=\"h-x-container style-1292 style-local-1797-c15 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-x-container-inner style-dynamic-1797-c15-group style-1292-spacing style-local-1797-c15-spacing\"><span class=\"h-button__outer style-1293-outer style-local-1797-c16-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"https:\/\/brainarts.nl\/de\/dies-ist-die-kontakt-und-adressseite-des-psychologen-brainarts-utrecht\/\" data-colibri-id=\"1797-c16\" class=\"d-flex w-100 align-items-center h-button justify-content-lg-center justify-content-md-center justify-content-center style-1293 style-local-1797-c16 position-relative\"><!----><!----> <span>Kontakt aufnehmen<\/span><\/a>\n                    <\/span>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Het financi\u00eble aspect Hieronder vindt je een zo volledig mogelijk overzicht van alle zaken omtrent vergoedingen, verzekeraars en opties om een zelf betalende client te worden. Als je vragen hebt, neem dan contact met ons op. We helpen je graag. Niet gecontracteerde zorg Wij werken niet met contracten met zorgverzekeraars. Dit houdt in dat je [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width-page.php","meta":{"footnotes":""},"class_list":["post-1797","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vergoedingen, zorgverzekering en zelfbetalen. - BrainArts Psycholoog<\/title>\n<meta name=\"description\" content=\"Alle informatie over vergoedingen, zorgverzekering en zelfbetalen. Je hoeft bij ons niet bij te betalen als het via je zorgverzekering gaat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brainarts.nl\/de\/erstattungen-von-krankenkassen-und-selbstzahler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vergoedingen, zorgverzekering en zelfbetalen.\" \/>\n<meta property=\"og:description\" content=\"Alle informatie over vergoedingen, zorgverzekering en zelfbetalen. Je hoeft bij ons niet bij te betalen als het via je zorgverzekering gaat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brainarts.nl\/de\/erstattungen-von-krankenkassen-und-selbstzahler\/\" \/>\n<meta property=\"og:site_name\" content=\"BrainArts Psycholoog\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T09:45:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Erstattungen, Krankenkassen und Selbstzahler. - BrainArts Psychologe","description":"Alle Informationen zu Erstattungen, Krankenversicherungen und Selbstzahlern. Bei uns m\u00fcssen Sie nicht extra bezahlen, wenn Sie \u00fcber Ihre Krankenkasse versichert sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brainarts.nl\/de\/erstattungen-von-krankenkassen-und-selbstzahler\/","og_locale":"de_DE","og_type":"article","og_title":"Vergoedingen, zorgverzekering en zelfbetalen.","og_description":"Alle informatie over vergoedingen, zorgverzekering en zelfbetalen. Je hoeft bij ons niet bij te betalen als het via je zorgverzekering gaat.","og_url":"https:\/\/brainarts.nl\/de\/erstattungen-von-krankenkassen-und-selbstzahler\/","og_site_name":"BrainArts Psycholoog","article_modified_time":"2025-02-25T09:45:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/","url":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/","name":"Erstattungen, Krankenkassen und Selbstzahler. - BrainArts Psychologe","isPartOf":{"@id":"https:\/\/brainarts.nl\/#website"},"datePublished":"2022-11-07T13:06:48+00:00","dateModified":"2025-02-25T09:45:36+00:00","description":"Alle Informationen zu Erstattungen, Krankenversicherungen und Selbstzahlern. Bei uns m\u00fcssen Sie nicht extra bezahlen, wenn Sie \u00fcber Ihre Krankenkasse versichert sind.","breadcrumb":{"@id":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brainarts.nl\/vergoedingen-zorgverzekering-en-zelfbetalen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brainarts.nl\/"},{"@type":"ListItem","position":2,"name":"Vergoedingen, zorgverzekering en zelfbetalen."}]},{"@type":"WebSite","@id":"https:\/\/brainarts.nl\/#website","url":"https:\/\/brainarts.nl\/","name":"BrainArts-Psychologe","description":"Lets redesign Your mind","publisher":{"@id":"https:\/\/brainarts.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brainarts.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/brainarts.nl\/#organization","name":"BrainArts-Psychologe","url":"https:\/\/brainarts.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/brainarts.nl\/#\/schema\/logo\/image\/","url":"https:\/\/brainarts.nl\/wp-content\/uploads\/2023\/01\/cropped-cropped-BrainArts-logo-transparant-1.webp","contentUrl":"https:\/\/brainarts.nl\/wp-content\/uploads\/2023\/01\/cropped-cropped-BrainArts-logo-transparant-1.webp","width":189,"height":189,"caption":"BrainArts Psycholoog"},"image":{"@id":"https:\/\/brainarts.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/brainarts.nl\/de\/wp-json\/wp\/v2\/pages\/1797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brainarts.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brainarts.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brainarts.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brainarts.nl\/de\/wp-json\/wp\/v2\/comments?post=1797"}],"version-history":[{"count":0,"href":"https:\/\/brainarts.nl\/de\/wp-json\/wp\/v2\/pages\/1797\/revisions"}],"wp:attachment":[{"href":"https:\/\/brainarts.nl\/de\/wp-json\/wp\/v2\/media?parent=1797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}